{"id":234883,"date":"2022-03-11T07:36:01","date_gmt":"2022-03-11T07:36:01","guid":{"rendered":"https:\/\/www.swissbionic.com\/pemf\/"},"modified":"2025-12-02T07:54:26","modified_gmt":"2025-12-02T07:54:26","slug":"cemp","status":"publish","type":"page","link":"https:\/\/scenarworks.swissbionic.com\/it\/cemp\/","title":{"rendered":"CEMP"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;dh-valign-center-section&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_color_gradient_start=&#8221;#ffffff&#8221; background_color_gradient_end=&#8221;#e5e5e5&#8243; background_image=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/pemf_01.jpg&#8221; parallax=&#8221;on&#8221; min_height=&#8221;90vh&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;45px&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;29px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; header_text_shadow_style=&#8221;preset1&#8243; header_text_shadow_vertical_length=&#8221;0em&#8221; header_text_shadow_color=&#8221;#000000&#8243; header_2_text_shadow_style=&#8221;preset1&#8243; header_2_text_shadow_vertical_length=&#8221;0em&#8221; header_2_text_shadow_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>PEMF<\/h1>\n<h2>Campi elettromagnetici pulsati<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Un campo elettromagnetico (anche EMF o EM-field) \u00e8 una quantit\u00e0 fisica prodotta da oggetti caricati elettricamente. I quattro parametri cruciali che definiscono la struttura del segnale esposto sono:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Forma d\u2019onda&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf83e;||fa||900&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Intensit\u00e0 del campo&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0e3;||divi||400&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;250ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Frequenza&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf773;||fa||900&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;500ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Risonanza&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0f5;||divi||400&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;750ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>In teoria, queste 4 componenti devono essere accuratamente disposte in equilibrio reciproco (coerenza) e introdotte nel corpo per produrre l\u2019effetto ottimale di promozione della salute e allo stesso tempo per evitare effetti negativi. La composizione dei parametri di base a cui si \u00e8 esposti differenzia se un segnale elettromagnetico \u00e8 dannoso (ad es. da sistemi informatici, telefoni cellulari, WIFI, Bluetooth, microonde, linee elettriche, ecc.) o favorevole alla salute, ad es. campi elettromagnetici pulsati a bassa frequenza (PEMF) utilizzato in ambito sanitario, per la profilassi e il benessere generale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;waveform&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_2_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Forma d\u2019onda<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Un\u2019onda \u00e8 un perturbazione che viaggia attraverso lo spazio, trasferendo energia da un punto all\u2019altro. Quelli di noi che hanno studiato fisica o algebra hanno familiarit\u00e0 con la rappresentazione grafica delle onde sinusoidali. Matematicamente, le onde sinusoidali possono essere disegnate su un sistema di coordinate costituito da assi \u201cx\u201d e \u201cy\u201d. L\u2019asse y contiene valori sia positivi che negativi. Un\u2019onda sinusoidale varia ciclicamente sia sopra che sotto l\u2019asse y ed \u00e8 simmetrica rispetto all\u2019asse zero (o asse x). Il valore pi\u00f9 positivo \u00e8 al \u201cpicco\u201d dell\u2019onda sinusoidale. Questa \u00e8 chiamata \u201campiezza di picco\u201d e rappresenta il punto di massimo spostamento del segnale magnetico da zero. Nella medicina biofisica, l\u2019ampiezza di picco o l\u2019intensit\u00e0 dell\u2019onda viene solitamente misurata in microTesla (in precedenza: Gauss).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_3_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Onda sinusoidale<\/h3>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/sinuswave-1.png&#8221; title_text=&#8221;sinuswave&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; scroll_horizontal_motion_enable=&#8221;on&#8221; scroll_horizontal_motion=&#8221;0|50|50|100|-2|0|2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]Un\u2019onda magnetica che ha polarit\u00e0 alternate (ad esempio picchi o cicli sia positivi che negativi) \u00e8 chiamata onda bipolare. Le forme e i comportamenti dei segnali magnetici possono essere manipolati alterando le correnti elettriche che li generano. Questo di solito \u00e8 fatto da computer programmati. Combinando cicli di pulsazioni magnetiche generate elettricamente, \u00e8 possibile creare \u201ctreni di impulsi\u201d che potenziano gli effetti biologici dello stimolo magnetico.<\/p>\n<p>La componente pi\u00f9 critica della forma d\u2019onda \u00e8 il suo tempo di salita e il tempo di caduta. Secondo Liboff, il valore terapeutico di un dato segnale pulsato dipende fortemente dalla rapidit\u00e0 con cui si verificano il tempo di salita e il tempo di caduta. Questa caratteristica del segnale non pu\u00f2 essere sottovalutata ed \u00e8 forse il parametro pi\u00f9 importante di un segnale elettromagnetico. Il tempo di caduta improvviso rappresenta un valore di tensione di picco elevato responsabile dello spostamento ionico nel corpo. Un maggiore spostamento ionico esercita un effetto biologico pi\u00f9 forte. Pi\u00f9 efficaci di una semplice onda sinusoidale o di un magnete statico, i sistemi iMRS prime e Omnium1 generano forme d\u2019onda fisiche molto complesse che producono risultati favorevoli alla salute. La cosiddetta forma del segnale a dente di sega e anche la forma d\u2019onda quadra creano tempi di salita e discesa molto pi\u00f9 bruschi rispetto a una semplice onda sinusoidale, portando a un maggiore effetto biologico.<br \/>\nNel complesso, la forma d\u2019onda o la forma del segnale elettromagnetico \u00e8 qualcosa a cui occorre prestare molta attenzione. La forma d\u2019onda pi\u00f9 efficace e complessa per risultati olistici che promuovono la salute \u00e8 l\u2019onda a dente di sega.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_3_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Onda quadra<\/h3>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/squarewave-1.png&#8221; title_text=&#8221;squarewave&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; scroll_horizontal_motion_enable=&#8221;on&#8221; scroll_horizontal_motion=&#8221;0|50|50|100|2|0|-2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_3_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Onda a dente di sega<\/h3>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/tripple_sawtooth-1.png&#8221; title_text=&#8221;tripple_sawtooth&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; scroll_horizontal_motion_enable=&#8221;on&#8221; scroll_horizontal_motion=&#8221;0|50|50|100|-2|0|2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>L\u2019evidenza clinica della forma d\u2019onda a dente di sega \u00e8 stata pubblicata per la prima volta dal ricercatore Bassett nel 1974. Il Dr. Bassett ha osservato che i cambiamenti nel segnale elettromagnetico inducono una corrente elettrica all\u2019interno del tessuto trattato. La corrente massima poteva essere misurata ogni volta che il segnale applicato scendeva bruscamente dal suo valore di picco al suo valore pi\u00f9 basso (tempo di caduta). Questa induzione \u201cpiezoelettrica\u201d all\u2019interno delle strutture ossee accelera la guarigione ossea. Come risultato del lavoro di Bassett, questa forma d\u2019onda \u00e8 stata approvata dalla FDA negli Stati Uniti dal 1979 per il trattamento delle fratture non consolidate e per aiutare nelle operazioni di fusione spinale.<\/p>\n<p>I sistemi iMRS prime e Omnium1 sono entrambi dotati di un applicatore di mat per tutto il corpo. La forma del segnale fornita dal tappetino \u00e8 una forma d\u2019onda a triplo dente di sega. Questa forma d\u2019onda \u00e8 un composto di un gran numero di onde armoniche, non sinusoidal, nella gamma delle basse frequenze. L\u2019impulso a dente di sega dell\u2019applicatore di tappetino iMRS prime e Omnium1 per tutto il corpo fornisce un intervallo di frequenza portante compreso tra 0,5 e 15 HZ, che \u00e8 del 100% all\u2019interno della cosiddetta \u201cfinestra biologica\u201d. A differenza delle semplici onde sinusoidali o dei magneti statici usurati esternamente, il segnale a dente di sega cambia continuamente, producendo un\u2019induzione costante di elettromagnetismo nei tessuti del corpo, massimizzando lo spostamento ionico e prevenendo l\u2019affaticamento della membrana cellulare. Ci\u00f2 significa che la membrana cellulare rimane reattiva ai segnali, migliorando e ottimizzando gli effetti benefici della stimolazione elettromagnetica. La ricerca ha dimostrato che la complessa forma d\u2019onda portante a triplo dente di sega, utilizzata dai tappetini per tutto il corpo iMRS prime e Omnium1, fornisce la pi\u00f9 alta probabilit\u00e0 di risonanza della stimolazione elettromagnetica nei tessuti viventi e quindi benefici superiori per la salute e il benessere.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;field_intensity&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Intensit\u00e0 del campo<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>L\u2019intensit\u00e0 di campo (nota anche come ampiezza o densit\u00e0 di flusso) \u00e8 una descrizione quantitativa di un campo elettromagnetico che dipende dal flusso e dalla direzione della corrente a cui \u00e8 stata assegnata l\u2019unit\u00e0 Tesla (T), in onore di Nikola Tesla, uno scienziato americano di origine serba che \u00e8 noto per i numerosi contributi rivoluzionari che ha dato nel campo dell\u2019elettricit\u00e0 e del magnetismo tra la fine del XIX e l\u2019inizio del XX secolo. \u201cGauss\u201d \u00e8 un\u2019unit\u00e0 pi\u00f9 vecchia per la densit\u00e0 di flusso, che \u00e8 ancora utilizzata come standard in diversi paesi del mondo (1 Gauss = 100 microTesla).<\/p>\n<p>I fattori determinanti dell\u2019intensit\u00e0 del campo (ampiezza) sono la lunghezza del filo della bobina magnetica, il diametro del filo, il numero di spire (o \u201cavvolgimenti\u201d) della bobina e l\u2019intensit\u00e0 della corrente elettrica (Ampere) applicata alla bobina E\u2019 possibile calcolare l\u2019intensit\u00e0 del campo (o densit\u00e0 di flusso) di un campo magnetico utilizzando insieme la costante di induzione e la resistenza specifica del materiale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/magnetfeld_erde.png&#8221; alt=&#8221;PEMF&#8221; title_text=&#8221;magnetfeld_erde&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; scroll_rotating_enable=&#8221;on&#8221; scroll_rotating=&#8221;0|50|50|100|-10\u00b0|0|10\u00b0&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>I sistemi diagnostici come la risonanza magnetica (MRI) utilizzano intensit\u00e0 di campo nell\u2019intervallo Tesla (1,5 &#8211; 3 T), i sistemi iMRS prime e Omnium1 emettono intensit\u00e0 di campo estremamente basse all\u2019interno dell\u2019intervallo in microTesla, inferiore di tre ordini di grandezza.<br \/>Poich\u00e9 l\u2019obiettivo della stimolazione \u00e8 la membrana cellulare, intensit\u00e0 estremamente basse sono adeguate per produrre una risposta biologica altamente benefica. Questa tesi si basa sul principio della \u201cfinestra biologica\u201d, un progetto di studio sviluppato, esplorato e pubblicato dal Dr. Ross Adey. Adey ha scoperto gamme specifiche e ristrette di frequenze elettromagnetiche a cui il corpo risponde con maggiore probabilit\u00e0. Questo principio pu\u00f2 essere ugualmente applicato all\u2019intensit\u00e0 del campo: esiste una \u201cfinestra biologica\u201d di intensit\u00e0 elettromagnetiche a cui il corpo umano risponde meglio e contribuisce alla rigenerazione cellulare attiva e al migliore apporto di ossigeno. La rispettiva ricerca di Goodman e Blank ha dimostrato che le cellule umane esprimono pi\u00f9 prontamente un gene di conservazione cellulare, la proteina da shock termico 70 (hsp70), a 7-8 microTesla piuttosto che a intensit\u00e0 di campo superiori a 70-100 microTesla.<\/p>\n<p>La \u201cmente\u201d originaria di una cellula umana, da una prospettiva elettromagnetica, reagisce meglio ad un sottile e gentile \u201csussurro\u201d.<\/p>\n<p>I sistemi iMRS prime e Omnium1 all\u2019avanguardia sono dotati di questo \u201clinguaggio\u201d originario e utilizzano intensit\u00e0 di campo estremamente basse che comunicano in modo pi\u00f9 efficace con la membrana cellulare. Il risultato \u00e8 il miglior effetto di salute possibile su tutte le cellule del corpo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;frequency&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Frequenza<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Proprio come le nostre cellule possono essere attivate per svolgere nuove e diverse funzioni mediante la stimolazione con sostanze chimiche (ad esempio, sostanze nutritive o farmaci), possono anche essere attivate energeticamente con onde elettromagnetiche. In effetti, alcune funzioni cellulari molto utili sono stimolate in modo pi\u00f9 efficace dall\u2019energia che dalla chimica. La larghezza di banda delle frequenze elettromagnetiche buona per la salute \u00e8 stata scientificamente provata. Queste gamme di frequenze sono chiamate \u201cfinestre biologiche\u201d. Finch\u00e9 la frequenza di erogazione rientra in questa finestra, conferir\u00e0 benefici alla cellula in termini di assunzione di nutrienti, eliminazione dei prodotti di scarto del metabolismo e funzione cellulare complessiva. Questo \u00e8 esattamente ci\u00f2 che fanno i sistemi iMRS prime e Omnium1; forniscono i modelli di frequenza corretti all\u2019interno delle finestre biologiche della salute!<\/p>\n<p>Un\u2019analogia sarebbero le frequenze acustiche. Alcuni suoni sono troppo forti per essere ascoltati, altri sono troppo deboli per essere uditi. C\u2019\u00e8 una piccola \u201cfinestra\u201d di volume all\u2019interno, che crea un\u2019esperienza uditiva piacevole e persino salutare. Lo stesso principio si applica all\u2019elettromagnetismo. Ci sono frequenze elettromagnetiche piacevoli e salutari; altre che sono troppo deboli per essere assimilate o percepite dal corpo e altre che sono cos\u00ec \u201crumorose\u201d che le cellule sono influenzate negativamente da tali segnali. Quei segnali nocivi e dannosi sono chiamati \u201celettrosmog\u201d.<\/p>\n<p>Gli applicatori a corpo intero iMRS PRIME e Omnium1 utilizzano 3 coppie di bobine di rame solido non isolate con quantit\u00e0 variabili di avvolgimenti per simulare le frequenze elettromagnetiche e le intensit\u00e0 del campo magnetico terrestre. Sappiamo dalla natura che tali frequenze sono in perfetta armonia con la salute e il benessere. L\u2019uso quotidiano di un applicatore per tutto il corpo favorisce l\u2019eliminazione di stress e tensioni, incoraggiando un maggiore apporto di ossigeno, aumentando la circolazione e migliorando il modo in cui il tuo corpo lavora a livello cellulare.<\/p>\n<p>Il tasso di cambiamento in un\u2019onda \u00e8 la sua \u201cfrequenza\u201d. Le onde ondeggiano da picco a valle a picco. Il tempo da un picco al picco successivo \u00e8 un ciclo. Un ciclo comprende un picco positivo (sopra la linea) e un picco negativo. L\u2019unit\u00e0 di base della frequenza \u00e8 un ciclo al secondo. Un ciclo al secondo (cps) viene anche chiamato un \u201chertz\u201d, in onore del fisico tedesco del XIX secolo Heinrich Hertz, la cui scoperta delle onde elettromagnetich ha portato allo sviluppo della radio. Una frequenza di 25 Hertz (Hz) rappresenta 25 cicli al secondo.<br \/>La frequenza viene misurata da un picco al picco successivo. L\u2019applicazione dell\u2019onda sinusoidale \u00e8 una modalit\u00e0 semplice mediante la quale l\u2019energia viene trasferita verso un mezzo (come il corpo); pi\u00f9 cicli al secondo, maggiore \u00e8 il trasferimento di energia al secondo. Siamo piuttosto consapevoli dell\u2019energia luminosa e comprendiamo le onde di luce (fotoni). Tuttavia, lo spettro della luce visibile \u00e8 solo una porzione molto piccola dello spettro elettromagnetico.<\/p>\n<p>Allo stesso modo, il suono udibile \u00e8 una piccola fetta dello spettro di frequenza del suono (acustico) e l\u2019orecchio umano pu\u00f2 rilevare e rispondere solo a una piccola parte delle frequenze che si trovano all\u2019interno di questo spettro. Con riferimento al trasferimento di segnali bioelettromagnetici vale la seguente regola generale: maggiore \u00e8 la frequenza, maggiore \u00e8 l\u2019energia fornita al corpo. Ma comprendendo il principio di Adey della \u201cfinestra biologica\u201d, sappiamo che, proprio come la luce e il suono, il corpo umano \u00e8 in grado di rispondere in modo benefico e salutare solo a una piccola gamma dello spettro di frequenze elettromagnetiche (effetto coerenza).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/frequencies.png&#8221; title_text=&#8221;frequencies&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; scroll_horizontal_motion_enable=&#8221;on&#8221; scroll_horizontal_motion=&#8221;0|50|50|100|1|0|-1&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Molti produttori di sistemi PEMF per uso domestico si vantano di quella maggiore potenza e del suo presunto vantaggio, fedele al motto: \u201cPi\u00f9 siamo, meglio \u00e8!\u201d. Noi di Swissbionic Solutions, tuttavia, comprendiamo che la medicina energetica applicata clinicamente non funziona necessariamente in questo modo. Le frequenze naturali all\u2019interno delle collaudate finestre biologiche sono le pi\u00f9 efficaci nel supportare salute e benessere vibranti &#8211; in sostanza: \u201cLess is more\u201d! Nella terapia PEMF, ci si riferisce ai cicli come impulsi. Pertanto, i cicli al secondo sono intesi come impulsi al secondo. Una frequenza elettromagnetica di 25 Hz \u00e8 quindi composta da 25 impulsi al secondo. Il corpo umano contiene molte frequenze naturali. Tra questi ci sono il battito cardiaco, il flusso del liquido cerebrospinale, il ritmo respiratorio e le onde elettromagnetiche del cervello. John Zimmerman, ex PhD presso l\u2019Universit\u00e0 del Colorado, ha documentato che la mano di un professionista di terapia manuale emette una frequenza elettromagnetica in media tra 7-8 Hz quando il professionista \u00e8 attivamente impegnato nell\u2019utilizzo del tocco curativo. \u00c8 interessante notare che le risonanze di Schumann prodotte all\u2019interno della ionosfera terrestre sono scientificamente valutate a 7,83 Hz. Il campo magnetico terrestre \u00e8 stato scientificamente calcolato in un intervallo compreso tra 11,75 e 11,79 Hz (Piontzik). Le onde alfa del cervello sembrano essere molto simili, se non praticamente identiche alle frequenze naturali di Schumann.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;schumann_resonance&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Risonanza Schumann<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Nel 1954 Schumann e K\u00f6nig riferirono della loro scoperta di pulsazioni elettromagnetiche presenti in natura sulla Terra. Le risonanze di Schumann sono onde naturali eccitate dai fulmini nella cavit\u00e0 tra la superficie terrestre e la ionosfera. In sostanza, i fulmini pompano energia nella cavit\u00e0 dell\u2019atmosfera terrestre e la fanno vibrare o risuonare a frequenze estremamente basse. Le onde elettromagnetiche create dai fulmini viaggiano intorno alla Terra alla velocit\u00e0 della luce, riflettendosi dalla ionosfera alla terra e viceversa in modo ciclico. Queste onde circumnavigano il globo con una media di 7,83 volte al secondo. Come notato sopra, questa frequenza \u00e8 correlata alla frequenza media delle onde cerebrali alfa negli esseri umani. La frequenza portante del campo magnetico terrestre \u00e8 scientificamente documentata e valutata a 11,75 &#8211; 11,79 HZ (Piontzik).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;#000000&#8243; next_background_color=&#8221;#000000&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/schumann3.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; top_divider_style=&#8221;wave2&#8243; bottom_divider_style=&#8221;wave2&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50vh&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]La frequenza portante delle risonanze di Schumann (\u201cfrequenza tonica\u201d) \u00e8 esattamente 7,83 Hz. Un armonico \u00e8 definito come un tono pi\u00f9 alto della frequenza di base all&#8217;interno di un sistema vibrazionale. Chi canta o suona la chitarra ha familiarit\u00e0 con la creazione di armonici, frequenze sonore che spesso vengono create sovrapponendo una frequenza fondamentale a un&#8217;altra. A causa della geometria sferica della Terra, si verificano ulteriori toni naturali a intervalli di 6,5 Hz. Ulteriori armoniche possono essere rilevate nel rumore radio di fondo del campo energetico terrestre come toni separati tra 14 e 35 Hz. Inoltre, queste armoniche sembrano essere benefiche per il nostro corpo.<\/p>\n<p>Il sistema genera forme d&#8217;onda (a dente di sega e quadrate) che, in base alle loro propriet\u00e0 fisiche, non solo forniscono grandi quantit\u00e0 di singole frequenze e le relative armoniche, ma anche i tempi di salita e discesa rapidi necessari per avviare e mantenere gli effetti di risonanza desiderati con il corpo.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;resonance&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Risonanza<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>La risonanza \u00e8 un principio che fu scoperto da Galileo Galilei nel 1602 mentre studiava i pendoli. La risonanza \u00e8 la tendenza di un sistema ad oscillare con la massima ampiezza a determinate frequenze.<\/p>\n<p>Un esempio comune di risonanza \u00e8 l\u2019altalena del parco giochi, che funge da pendolo. Se spingi un bambino su un\u2019altalena nel tempo con l\u2019intervallo naturale dell\u2019altalena (la sua frequenza di risonanza), l\u2019altalena andr\u00e0 sempre pi\u00f9 in alto (fino alla sua ampiezza massima). L\u2019applicazione di una forza di spinta in qualsiasi altro momento interferir\u00e0 o smorzer\u00e0 la frequenza di risonanza e l\u2019oscillazione verr\u00e0 ridotta in ampiezza, interrotta o interrotta completamente. L\u2019energia (spinta esterna) assorbita dallo swing \u00e8 massimizzata ogni volta che \u00e8 in sincronia (o \u201cin risonanza\u201d) con le oscillazioni dello swing stesso.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/resonance.jpg&#8221; title_text=&#8221;resonance&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;250ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Ogni cellula del corpo umano vibra o oscilla. Questo pu\u00f2 essere osservato visivamente nelle riprese video ad alto ingrandimento quando i globuli rossi viaggiano attraverso vasi o macrofagi inseguendo i batteri. I campi elettromagnetici pulsati con uno spettro di frequenza appropriato sono in grado di produrre risonanza cellulare = vibrazione alla massima ampiezza. Attivano le rispettive frequenze portanti dei recettori (neuropeptidi) con l\u2019obiettivo di stimolare una variet\u00e0 di funzioni intorno e all\u2019interno di ciascuna cellula. Il corpo umano \u00e8 costituito da circa 75 trilioni di cellule (a seconda delle dimensioni e del peso) mentre ogni membrana cellulare contiene oltre 1 milione di recettori neuropeptidi. Un campo elettromagnetico pulsante precisamente definito all\u2019interno della finestra biologica stimola tutti questi recettori simultaneamente alla velocit\u00e0 della luce e li incoraggia a risuonare con le vibrazioni applicate. Questa \u00e8 la propriet\u00e0 essenziale di PEMF. I profondi effetti benefici nella fisiologia umana attraverso i PEMF iniziano attraverso una migliore comunicazione e interazione inter e intracellulare prodotta dall\u2019induzione della risonanza all\u2019interno del corpo. Ad oggi non \u00e8 scientificamente provato che le frequenze al di fuori della finestra biologica siano in grado di creare effetti risonanti sulle strutture cellulari.<\/p>\n<p>Maggiore \u00e8 la frequenza, pi\u00f9 difficile \u00e8 valutare l\u2019effetto sulla cellula. \u00c8 importante sottolineare che ci\u00f2 si applica alle frequenze \u201cinnaturali\u201d nella gamma KHz e MHz esposte da telefoni domestici wireless, smartphone, router WIFI e molti dispositivi elettrici domestici comuni. La generazione pi\u00f9 recente ed efficace di sistemi PEMF certificati dal punto di vista medico, l\u2019iMRS PRIME o Omnium1, mira alla gamma di frequenze estremamente basse, in corrispondenza con le note vibrazioni toniche oscillatorie delle cellule del corpo. Rappresentano il gold standard dell\u2019utilizzo di modelli avanzati di risonanza stocastica computerizzata per ottenere la massima risonanza cellulare.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;biological_window&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Finestra biologica<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/biological_window.jpg&#8221; title_text=&#8221;biological_window&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;250ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il dottor William Ross Adey, un professore di anatomia e fisiologia nato in Australia che lavora presso la UCLA School of Medicine, ha coniato il termine \u201cfinestra biologica\u201d. (Bawin e Adey 1976) Adey ha misurato la produzione di calcio delle cellule cerebrali nei conigli per dimostrare che questo effetto poteva essere attivato solo utilizzando intensit\u00e0 di campo magnetico molto basse e una specifica bassa frequenza (16 Hz). Dalla scoperta iniziale del Dr. Adey, la letteratura sulla medicina energetica ha mostrato un forte consenso scientifico sull\u2019importanza delle finestre biologiche.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Una finestra biologica \u00e8 un intervallo o spettro di energie elettromagnetiche che sono prontamente accettate dal corpo e convertite in risposte fisiologiche positive. I segnali che escono dalla finestra biologica hanno scarso o nessun effetto, o in alcuni casi anche un effetto negativo o tossico. Per analogia, le frequenze udibili possono essere piacevoli (ad esempio, una sinfonia) o possono essere distruttive (ad esempio, il suono di un\u2019esplosione pu\u00f2 distruggere permanentemente l\u2019udito). La ricerca ha dimostrato che i tessuti viventi rilevano, assorbono e utilizzano prontamente i segnali elettromagnetici all\u2019interno di determinate gamme di frequenza e ignorano completamente altre frequenze che si incontrano naturalmente nello spettro di frequenza.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_id=&#8221;organ_clock&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>L\u2019orologio degli organi<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Gli applicatori per tutto il corpo dei sistemi iMRS PRIME e Omnium1 utilizzano schemi di frequenza preprogrammati che variano in base all\u2019ora del giorno in cui viene utilizzato il dispositivo. La base per questa variazione temporale della frequenza sono i ritmi circadiani naturalmente osservati. Questo fenomeno \u00e8 stato scientificamente provato ed lo scienziato \u00e8 stato insignito del Premio Nobel per la Medicina 2017 (Hall, Rosbash and Young: Discoveries of Molecular Mechanisms Controlling the Circadian Rhythm). Secondo la Medicina Tradizionale Cinese (e altre antiche tradizioni curative in Asia) l\u2019energia vitale scorre attraverso i dodici organi e compie un ciclo ogni ventiquattro ore. L\u2019orologio cinese degli organi mostra il flusso circadiano dell\u2019energia vitale (Qi &#8211; pronunciato \u201cChi\u201d) attraverso vari sistemi e organi in relazione all\u2019ora del giorno. Ogni organo ha la massima energia per due ore. L\u2019organo ha energia minima (o flusso pi\u00f9 basso di Qi) 12 ore dopo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<table class=\"table_organ_clock\">\n<tbody>\n<tr>\n<th style=\"width: 33.3333%;\">TEMPO<\/th>\n<th style=\"width: 33.3333%;\">MASSIMA ENERGIA<\/th>\n<th style=\"width: 33.3333%;\">ORGANO\/MERIDIANO<\/th>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">03:00 &#8211; 05:00<\/td>\n<td style=\"width: 33.3333%;\">04:00<\/td>\n<td style=\"width: 33.3333%;\">POLMONE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">05:00 &#8211; 07:00<\/td>\n<td style=\"width: 33.3333%;\">06:00<\/td>\n<td style=\"width: 33.3333%;\">INTESTINO GRASSO<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">07:00 &#8211; 09:00<\/td>\n<td style=\"width: 33.3333%;\">08:00<\/td>\n<td style=\"width: 33.3333%;\">STOMACO<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">09:00 &#8211; 11:00<\/td>\n<td style=\"width: 33.3333%;\">10:00<\/td>\n<td style=\"width: 33.3333%;\">MILZA<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">11:00 &#8211; 13:00<\/td>\n<td style=\"width: 33.3333%;\">12:00<\/td>\n<td style=\"width: 33.3333%;\">CUORE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">13:00 &#8211; 15:00<\/td>\n<td style=\"width: 33.3333%;\">14:00<\/td>\n<td style=\"width: 33.3333%;\">INTESTINO TENUE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">15:00 &#8211; 17:00<\/td>\n<td style=\"width: 33.3333%;\">16:00<\/td>\n<td style=\"width: 33.3333%;\">VESCICA URINARIA<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">17:00 &#8211; 19:00<\/td>\n<td style=\"width: 33.3333%;\">18:00<\/td>\n<td style=\"width: 33.3333%;\">RENE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">19:00 &#8211; 21:00<\/td>\n<td style=\"width: 33.3333%;\">20:00<\/td>\n<td style=\"width: 33.3333%;\">PERICARDIO<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">21:00 &#8211; 23:00<\/td>\n<td style=\"width: 33.3333%;\">22:00<\/td>\n<td style=\"width: 33.3333%;\">TRIPLICE RISCALDATORE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">23:00 &#8211; 01:00<\/td>\n<td style=\"width: 33.3333%;\">00:00<\/td>\n<td style=\"width: 33.3333%;\">VESCICA BILIARE<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 33.3333%;\">01:00 &#8211; 03:00<\/td>\n<td style=\"width: 33.3333%;\">02:00<\/td>\n<td style=\"width: 33.3333%;\">FEGATO<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; background_image=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/organuhr_italiano_2.png&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; height=&#8221;100vh&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22background_color%22%93}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; height=&#8221;50vh&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Dal grafico sopra si pu\u00f2 vedere che il flusso massimo di energia attraverso il fegato \u00e8 alle 2 del mattino. Pertanto, il flusso di energia corrispondente pi\u00f9 basso del fegato \u00e8 alle 14:00. I sistemi iMRS PRIME e Omnium1 forniscono pacchetti di impulsi di energia che si ritiene riequilibrino la risonanza cellulare per tutti gli organi e i sistemi corporei contemporaneamente variando le frequenze attraverso 4 intervalli preprogrammati:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;5:00 &#8211; 10:00&#8243; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe031;||divi||400&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;10:00 &#8211; 15:00&#8243; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe031;||divi||400&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;250ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;15:00 &#8211; 20:00&#8243; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe031;||divi||400&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;500ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;20:00 &#8211; 5:00&#8243; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe031;||divi||400&#8243; icon_color=&#8221;gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45&#8243; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;22px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;750ms&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{%22gcid-9051e08e-43f1-4c38-ba24-3820c0f15a45%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>I pacchetti di impulsi forniti dall\u2019applicatore di tappetino per tutto il corpo di iMRS prime o Omnium1 utilizzano la forma del segnale a triplo dente di sega, complessa e altamente efficace e sono composti da un gran numero di singole frequenze elettromagnetiche nella gamma di frequenze estremamente basse (ELF). Permette di trasferire un massimo di singole frequenze e le sue armoniche in applicazioni di breve durata (8-24 min.). Ogni 2 minuti durante questa stimolazione la polarit\u00e0 viene invertita per prevenire l\u2019affaticamento cellulare e l\u2019adattamento al segnale. Questo concetto ha lo scopo di massimizzare l\u2019efficacia terapeutica.<\/p>\n<p>Gli applicatori Pad e Spot pi\u00f9 piccoli sono in grado di ottenere intensit\u00e0 di campo pi\u00f9 elevate e sono versatili nel modo in cui vengono applicati esternamente al corpo. Non \u00e8 necessaria una regolazione dell\u2019orologio d\u2019organo per questi applicatori poich\u00e9 l\u2019obiettivo di un\u2019applicazione PEMF locale \u00e8 affrontare un\u2019indicazione isolata (guarigione della ferita, guarigione ossea, aumento periferico della circolazione sanguigna, sollievo dal dolore) Una specifica forma d\u2019onda rettangolare (onda quadra) viene utilizzato per ottenere i risultati migliori e pi\u00f9 rapidi.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#A8343A&#8221; top_divider_height=&#8221;60px&#8221; da_disable_devices=&#8221;off|off|off&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.swissbionic.com\/wp-content\/uploads\/brochure_pemf_en.png&#8221; alt=&#8221;BUYERS GUIDE&#8221; title_text=&#8221;brochure_pemf_en&#8221; url=&#8221;https:\/\/backoffice.swissbionic.com\/documents\/flyer\/pemf_in_a_nutshell_it.pdf&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;20%&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.17.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; header_2_text_align_tablet=&#8221;center&#8221; header_2_text_align_phone=&#8221;&#8221; header_2_text_align_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>I PEMF in breve<\/h2>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/backoffice.swissbionic.com\/documents\/flyer\/pemf_in_a_nutshell_it.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Scarica qui&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;&#8221; button_alignment_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#A8343A&#8221; button_bg_color=&#8221;#FFFFFF&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;3px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;20%&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PEMF Campi elettromagnetici pulsatiUn campo elettromagnetico (anche EMF o EM-field) \u00e8 una quantit\u00e0 fisica prodotta da oggetti caricati elettricamente. I quattro parametri cruciali che definiscono la struttura del segnale esposto sono:In teoria, queste 4 componenti devono essere accuratamente disposte in equilibrio reciproco (coerenza) e introdotte nel corpo per produrre l\u2019effetto ottimale di promozione della salute [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/pages\/234883"}],"collection":[{"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/comments?post=234883"}],"version-history":[{"count":3,"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/pages\/234883\/revisions"}],"predecessor-version":[{"id":237193,"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/pages\/234883\/revisions\/237193"}],"wp:attachment":[{"href":"https:\/\/scenarworks.swissbionic.com\/it\/wp-json\/wp\/v2\/media?parent=234883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}